{"id":3002,"date":"2016-01-30T12:42:29","date_gmt":"2016-01-30T11:42:29","guid":{"rendered":"http:\/\/artblobs.com\/?p=3002"},"modified":"2023-07-06T23:58:15","modified_gmt":"2023-07-06T21:58:15","slug":"la-parola-allartista-intervista-a-massimo-balestrini","status":"publish","type":"post","link":"https:\/\/artblobs.com\/en\/2016\/01\/interview-with-the-artist-massimo-balestrini\/","title":{"rendered":"Interview with the artist Massimo Balestrini"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/artblobs.com\/it\/wp-json\/wp\/v2\/posts\/3002\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"Italiano\">Italiano<\/a>. For the sake of viewer convenience, the content is shown below in the alternative language. You may click the link to switch the active language.<\/p><div class='booster-block booster-read-block'>\n                <div class=\"twp-read-time\">\n                \t<i class=\"booster-icon twp-clock\"><\/i> <span>Read Time:<\/span>7 Minute, 31 Second                <\/div>\n\n            <\/div><p><\/p>\n<div class=\"textimage\">\n<p class=\"textnexttoimg\" style=\"text-align: justify;\"><b>L\u2019artista. Breve biografia.<\/b><\/p>\n<p class=\"textnexttoimg\" style=\"text-align: justify;\">Nasce nel 1967 a Milano.<br \/>\nLa sua passione per le arti figurative ed in special modo per il disegno e le arti visive lo spingono a frequentare l\u2019Istituto d\u2019Arte Beato Angelico di Milano, dove consegue il diploma di Maestro d\u2019Arte e la Maturit\u00e0 d\u2019Arte Applicata nella sezione di Decorazione Pittorica.<br \/>\nNello stesso periodo scopre la passione per l\u2019uso del computer come nuovo mezzo creativo. In seguito, consegue una Laurea in Scienze dell\u2019Informazione presso l\u2019Universit\u00e0 di Milano e mai dimenticando l\u2019antico amore per l\u2019arte, si diploma con lode in Pittura presso l\u2019Accademia di Belle Arti di Brera dove, successivamente, collabora con il Prof. Filippo Panseca per Il Corso di Computer Painting.<br \/>\nAl concorso internazionale di computer graphics BitMovie 1995 \u00e8 tra i primi tre classificati. Lavora per Il Sole 24 Ore, Il Giorno, Virtual. Le sue opere si trovano in collezioni italiane e straniere.<br \/>\nAttualmente \u00e8 docente presso l\u2019Accademia Cignaroli di Belle Arti di Verona per il corso di: \u201cElaborazione digitale dell\u2019Immagine\u201d ed \u00e8 inoltre responsabile di sede e docente presso i laboratori distaccati di Torbole della Libera Accademia di Belle Arti Laba, per i dipartimenti di Design e Graphic Design e Multimedia.<\/p>\n<div id=\"maxgallery-3001\" class=\"mg-image-tiles borderless\">\t<div class=\"mg-thumbs mg-sixcol\">\t\t<ul><li>\t<a  data-rel=\"lightbox-image-bGlnaHRib3gtMA==\" data-rl_title=\"\" data-rl_caption=\"\" href='https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/SKYWAY-PATROL.jpg' target='' rel='mg-rel-image-thumbs' title=''>\t\t<div class=\"\"><img class=\"mg_lazy\" data-src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/SKYWAY-PATROL-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Skyway patrol, Massimo Balestrini, Mixed media on canvas, 2013\" title=\"Skyway patrol, Massimo Balestrini, Mixed media on canvas, 2013\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/SKYWAY-PATROL-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Skyway patrol, Massimo Balestrini, Mixed media on canvas, 2013\" \/><\/noscript>\t\t<\/div>\t<\/a><\/li><li>\t<a  data-rel=\"lightbox-image-bGlnaHRib3gtMA==\" data-rl_title=\"\" data-rl_caption=\"\" href='https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/JUNKYARD.jpg' target='' rel='mg-rel-image-thumbs' title=''>\t\t<div class=\"\"><img class=\"mg_lazy\" data-src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/JUNKYARD-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Junkyard, Massimo Balestrini, Mixed media on canvas, 2012\" title=\"Junkyard, Massimo Balestrini, Mixed media on canvas, 2012\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/JUNKYARD-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Junkyard, Massimo Balestrini, Mixed media on canvas, 2012\" \/><\/noscript>\t\t<\/div>\t<\/a><\/li><li>\t<a  data-rel=\"lightbox-image-bGlnaHRib3gtMA==\" data-rl_title=\"\" data-rl_caption=\"\" href='https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/02_cosmos.jpg' target='' rel='mg-rel-image-thumbs' title=''>\t\t<div class=\"\"><img class=\"mg_lazy\" data-src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/02_cosmos-180x120.jpg\" width=\"180\" height=\"120\" alt=\"People need heros, Massimo Balestrini, Mixed media on canvas, 2010\" title=\"People need heros, Massimo Balestrini, Mixed media on canvas, 2010\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/02_cosmos-180x120.jpg\" width=\"180\" height=\"120\" alt=\"People need heros, Massimo Balestrini, Mixed media on canvas, 2010\" \/><\/noscript>\t\t<\/div>\t<\/a><\/li><li>\t<a  data-rel=\"lightbox-image-bGlnaHRib3gtMA==\" data-rl_title=\"\" data-rl_caption=\"\" href='https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/peopmind.jpg' target='' rel='mg-rel-image-thumbs' title=''>\t\t<div class=\"\"><img class=\"mg_lazy\" data-src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/peopmind-180x120.jpg\" width=\"180\" height=\"120\" alt=\"People&#039;s mind, Massimo Balestrini, Mixed media on canvas, 2008\" title=\"People&#039;s mind, Massimo Balestrini, Mixed media on canvas, 2008\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/peopmind-180x120.jpg\" width=\"180\" height=\"120\" alt=\"People&#039;s mind, Massimo Balestrini, Mixed media on canvas, 2008\" \/><\/noscript>\t\t<\/div>\t<\/a><\/li><li>\t<a  data-rel=\"lightbox-image-bGlnaHRib3gtMA==\" data-rl_title=\"\" data-rl_caption=\"\" href='https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/MAINSTREAM.jpg' target='' rel='mg-rel-image-thumbs' title=''>\t\t<div class=\"\"><img class=\"mg_lazy\" data-src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/MAINSTREAM-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Mainstream, Massimo Balestrini, Mixed media on canvas, 2012\" title=\"Mainstream, Massimo Balestrini, Mixed media on canvas, 2012\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/MAINSTREAM-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Mainstream, Massimo Balestrini, Mixed media on canvas, 2012\" \/><\/noscript>\t\t<\/div>\t<\/a><\/li><li>\t<a  data-rel=\"lightbox-image-bGlnaHRib3gtMA==\" data-rl_title=\"\" data-rl_caption=\"\" href='https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/Home-YOU-CAN-CHANGE.jpg' target='' rel='mg-rel-image-thumbs' title=''>\t\t<div class=\"\"><img class=\"mg_lazy\" data-src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/Home-YOU-CAN-CHANGE-180x120.jpg\" width=\"180\" height=\"120\" alt=\"You can change the world, Massimo Balestrini, Mixed media on canvas, 2014\" title=\"You can change the world, Massimo Balestrini, Mixed media on canvas, 2014\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/Home-YOU-CAN-CHANGE-180x120.jpg\" width=\"180\" height=\"120\" alt=\"You can change the world, Massimo Balestrini, Mixed media on canvas, 2014\" \/><\/noscript>\t\t<\/div>\t<\/a><\/li><li>\t<a  data-rel=\"lightbox-image-bGlnaHRib3gtMA==\" data-rl_title=\"\" data-rl_caption=\"\" href='https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/Gone-with-the-Wind.jpg' target='' rel='mg-rel-image-thumbs' title=''>\t\t<div class=\"\"><img class=\"mg_lazy\" data-src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/Gone-with-the-Wind-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Gone with the wind, Massimo Balestrini, Mixed media on canvas, 2013\" title=\"Gone with the wind, Massimo Balestrini, Mixed media on canvas, 2013\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/Gone-with-the-Wind-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Gone with the wind, Massimo Balestrini, Mixed media on canvas, 2013\" \/><\/noscript>\t\t<\/div>\t<\/a><\/li><li>\t<a  data-rel=\"lightbox-image-bGlnaHRib3gtMA==\" data-rl_title=\"\" data-rl_caption=\"\" href='https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/freedom-sales.web_.jpg' target='' rel='mg-rel-image-thumbs' title=''>\t\t<div class=\"\"><img class=\"mg_lazy\" data-src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/freedom-sales.web_-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Freedom sales, Massimo Balestrini, Mixed media on canvas, 2006\" title=\"Freedom sales, Massimo Balestrini, Mixed media on canvas, 2006\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/freedom-sales.web_-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Freedom sales, Massimo Balestrini, Mixed media on canvas, 2006\" \/><\/noscript>\t\t<\/div>\t<\/a><\/li><li>\t<a  data-rel=\"lightbox-image-bGlnaHRib3gtMA==\" data-rl_title=\"\" data-rl_caption=\"\" href='https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/FOLLOW-ME.jpg' target='' rel='mg-rel-image-thumbs' title=''>\t\t<div class=\"\"><img class=\"mg_lazy\" data-src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/FOLLOW-ME-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Follow me, Massimo Balestrini, Mixed media on canvas, 2012\" title=\"Follow me, Massimo Balestrini, Mixed media on canvas, 2012\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/FOLLOW-ME-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Follow me, Massimo Balestrini, Mixed media on canvas, 2012\" \/><\/noscript>\t\t<\/div>\t<\/a><\/li><li>\t<a  data-rel=\"lightbox-image-bGlnaHRib3gtMA==\" data-rl_title=\"\" data-rl_caption=\"\" href='https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/tho.jpg' target='' rel='mg-rel-image-thumbs' title=''>\t\t<div class=\"\"><img class=\"mg_lazy\" data-src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/tho-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Thoughts, Massimo Balestrini, Mixed media on canvas, 2008\" title=\"Thoughts, Massimo Balestrini, Mixed media on canvas, 2008\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/tho-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Thoughts, Massimo Balestrini, Mixed media on canvas, 2008\" \/><\/noscript>\t\t<\/div>\t<\/a><\/li><li>\t<a  data-rel=\"lightbox-image-bGlnaHRib3gtMA==\" data-rl_title=\"\" data-rl_caption=\"\" href='https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/web.information_war.jpg' target='' rel='mg-rel-image-thumbs' title=''>\t\t<div class=\"\"><img class=\"mg_lazy\" data-src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/web.information_war-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Information war, Massimo Balestrini, Mixed media on canvas, 2007\" title=\"Information war, Massimo Balestrini, Mixed media on canvas, 2007\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/web.information_war-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Information war, Massimo Balestrini, Mixed media on canvas, 2007\" \/><\/noscript>\t\t<\/div>\t<\/a><\/li><li>\t<a  data-rel=\"lightbox-image-bGlnaHRib3gtMA==\" data-rl_title=\"\" data-rl_caption=\"\" href='https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/web.Lighter-than-air.jpg' target='' rel='mg-rel-image-thumbs' title=''>\t\t<div class=\"\"><img class=\"mg_lazy\" data-src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/web.Lighter-than-air-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Lighter than air, Massimo Balestrini, Mixed media on canvas, 2009\" title=\"Lighter than air, Massimo Balestrini, Mixed media on canvas, 2009\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/web.Lighter-than-air-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Lighter than air, Massimo Balestrini, Mixed media on canvas, 2009\" \/><\/noscript>\t\t<\/div>\t<\/a><\/li><li>\t<a  data-rel=\"lightbox-image-bGlnaHRib3gtMA==\" data-rl_title=\"\" data-rl_caption=\"\" href='https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/web.Time-Repair_flat.jpg' target='' rel='mg-rel-image-thumbs' title=''>\t\t<div class=\"\"><img class=\"mg_lazy\" data-src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/web.Time-Repair_flat-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Time repair, Massimo Balestrini, Mixed media on canvas, 2008\" title=\"Time repair, Massimo Balestrini, Mixed media on canvas, 2008\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/web.Time-Repair_flat-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Time repair, Massimo Balestrini, Mixed media on canvas, 2008\" \/><\/noscript>\t\t<\/div>\t<\/a><\/li><li>\t<a  data-rel=\"lightbox-image-bGlnaHRib3gtMA==\" data-rl_title=\"\" data-rl_caption=\"\" href='https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/web_JUMP.jpg' target='' rel='mg-rel-image-thumbs' title=''>\t\t<div class=\"\"><img class=\"mg_lazy\" data-src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/web_JUMP-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Jump, Massimo Balestrini, Mixed media on canvas, 2008\" title=\"Jump, Massimo Balestrini, Mixed media on canvas, 2008\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/web_JUMP-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Jump, Massimo Balestrini, Mixed media on canvas, 2008\" \/><\/noscript>\t\t<\/div>\t<\/a><\/li><li>\t<a  data-rel=\"lightbox-image-bGlnaHRib3gtMA==\" data-rl_title=\"\" data-rl_caption=\"\" href='https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/web_LOCAL_HERO.jpg' target='' rel='mg-rel-image-thumbs' title=''>\t\t<div class=\"\"><img class=\"mg_lazy\" data-src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/web_LOCAL_HERO-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Local hero, Massimo Balestrini, Mixed media on canvas, 2010\" title=\"Local hero, Massimo Balestrini, Mixed media on canvas, 2010\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/web_LOCAL_HERO-180x120.jpg\" width=\"180\" height=\"120\" alt=\"Local hero, Massimo Balestrini, Mixed media on canvas, 2010\" \/><\/noscript>\t\t<\/div>\t<\/a><\/li><li>\t<a  data-rel=\"lightbox-image-bGlnaHRib3gtMA==\" data-rl_title=\"\" data-rl_caption=\"\" href='https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/A-NEW-LIGHT.jpg' target='' rel='mg-rel-image-thumbs' title=''>\t\t<div class=\"\"><img class=\"mg_lazy\" data-src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/A-NEW-LIGHT-180x120.jpg\" width=\"180\" height=\"120\" alt=\"A new light, Massimo Balestrini, Mixed media on canvas\" title=\"A new light, Massimo Balestrini, Mixed media on canvas\" \/><noscript><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/A-NEW-LIGHT-180x120.jpg\" width=\"180\" height=\"120\" alt=\"A new light, Massimo Balestrini, Mixed media on canvas\" \/><\/noscript>\t\t<\/div>\t<\/a><\/li>\t\t<\/ul>\t\t<div class=\"clear\"><\/div>\t<\/div>\t<span style=\"display: none;\" class=\"hidden-image-tiles-gallery-id\">3001<\/span>\t<span style=\"display: none;\" class=\"hidden-lightbox-skin\">none<\/span>\t<span style=\"display: none;\" class=\"hidden-lightbox-effect\">none<\/span>\t<span style=\"display: none;\" class=\"hidden-lightbox-kb-nav\">true<\/span>\t<span style=\"display: none;\" class=\"hidden-lightbox-img-click-close\">true<\/span>\t<span style=\"display: none;\" class=\"hidden-lightbox-ol-click-close\">true<\/span>\t<span style=\"display: none;\" class=\"hidden-lightbox-close-tip-text\">Close<\/span>\t<span style=\"display: none;\" class=\"hidden-lightbox-next-tip-text\">Next<\/span>\t<span style=\"display: none;\" class=\"hidden-lightbox-prev-tip-text\">Previous<\/span>\t<span style=\"display: none;\" class=\"hidden-lightbox-error-tip-text\">The requested content cannot be loaded. Please try again later.<\/span><\/div><script>\ndocument.addEventListener(\"DOMContentLoaded\", function(event) { \njQuery(\"img.mg_lazy\").lazyload();\n});\n<\/script>\n\n<ol>\n<li class=\"textnexttoimg\" style=\"text-align: justify;\"><strong>Parlaci delle tue origini come artista. Quale voce interiore ti ha spinto ad avvicinarti al mondo dell\u2019arte?<\/strong><br \/>\nLa mia passione per il disegno nasce fin da bambino, nel momento in cui ho preso in mano una matita ho scoperto di amare pi\u00f9 di ogni altra cosa la possibilit\u00e0 di poter riprodurre quello che vedevo e quello che immaginavo.\u00a0 Trovo molto pi\u00f9 facile raccontare qualcosa rappresentandolo visivamente che dovendolo esporre a parole.<\/li>\n<\/ol>\n<ol start=\"2\">\n<li class=\"textnexttoimg\" style=\"text-align: justify;\"><strong>Cosa ti affascina nell\u2019utilizzo del pc come strumento artistico? <\/strong><br \/>\nHo avuto il mio primo computer negli anni &#8217;80, prima ancora dell&#8217;avvento del PC. L&#8217;uso di un mezzo digitale mi risulta ormai cos\u00ec naturale che lo considero una normale estensione del mio modo di progettare e dipingere. Mi hanno sempre affascinato tutte le potenzialit\u00e0 del mezzo che permettono di ottenere risultati altrimenti non possibili oppure che necessiterebbero mesi di lavoro.<\/li>\n<\/ol>\n<ol start=\"3\">\n<li class=\"textnexttoimg\" style=\"text-align: justify;\"><strong>Spesso hai citato il film Tron come tua fonte di ispirazione. <\/strong><br \/>\nIl film Tron (1982) \u00a0\u00e8 stato una pietra miliare nel mondo della computer grafica e ha segnato per tutti gli appassionati un momento di passaggio tra le tecniche analogiche a quelle digitali. Anche io come il protagonista del film sono stato risucchiato in una nuova realt\u00e0!<\/li>\n<\/ol>\n<ol start=\"4\">\n<li class=\"textnexttoimg\" style=\"text-align: justify;\"><strong>Quali artisti ti hanno ispirato? <\/strong><br \/>\nAmo molto l&#8217;arte moderna e tra i maggiori artisti del &#8216;900 ammiro sopratutto Picasso: &#8220;La pittura non \u00e8 fatta per decorare gli appartamenti.\u00a0\u00c8 uno strumento di guerra offensiva e difensiva contro il nemico&#8221;.\u00a0Questa frase mi ha sempre ispirato a realizzare opere che abbiano un contenuto, un messaggio. L&#8217;artista non ha un compito solo estetico, ha soprattutto un compito sociale e culturale. L&#8217;aspetto esteriore \u00e8 utilizzato per attirare l&#8217;attenzione, per destare interesse. Il messaggio invece \u00e8 quello che l&#8217;artista riesce a trasmettere, anche solo come emozioni, nell&#8217;osservatore.<\/li>\n<\/ol>\n<ol start=\"5\">\n<li class=\"textnexttoimg\" style=\"text-align: justify;\"><strong>Quali sono a tuo parere le maggiori contraddizioni del mondo contemporaneo?<\/strong><br \/>\nIl mondo contemporaneo, come penso ogni periodo della storia, \u00e8 dominato da poteri forti che in qualche modo determinano la sorte di milioni di persone. Politica, ideologia, religione, sono da sempre usati come paraventi,\u00a0 pretesti ed occasioni per perpetuare la supremazia di pochi sui tanti. Una guerra quasi invisibile \u00e8 da sempre in atto per il mantenimento di questa condizione. Le contraddizioni sono sotto gli occhi di tutti, ogni giorno. \u00a0E&#8217; pi\u00f9 facile ignorarle che combatterle.<strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/strong><\/li>\n<\/ol>\n<ol start=\"6\">\n<li class=\"textnexttoimg\" style=\"text-align: justify;\"><strong>\u201cThe magic door\u201d \u00e8 il titolo che hai scelto per una delle tue collezioni. In cosa auspica la Porta magica di Massimo Balestrini? <\/strong><br \/>\nLa porta magica \u00e8 ispirata alla porta iniziatica dell&#8217;alchimia, una sorta di passaggio tra una condizione impura ad una condizione di purezza. Nella mia idea rappresenta l&#8217;Etica. In un periodo dove si misura il grado sociale sulla ricchezza personale, parlare di etica \u00e8 una scelta forte, quasi anacronistica. In questa serie ho voluto rappresentare il denaro con una forma antropomorfa. In &#8216;fucking money&#8217; il denaro ha assunto addirittura una forma femminile dalle movenze sensuali.<\/li>\n<\/ol>\n<ol start=\"7\">\n<li class=\"textnexttoimg\" style=\"text-align: justify;\"><strong>Ulteriore famosa collezione \u00e8 \u201cThe way to truth\u201d. Cosa \u00e8 per te la verit\u00e0? <\/strong><br \/>\nNel vangelo Cristo afferma: \u00a0\u00abConoscerete la verit\u00e0 e la verit\u00e0 vi far\u00e0 liberi\u00bb (Gv 8,32).\u00a0 La ricerca della verit\u00e0 \u00e8 un compito sempre pi\u00f9 arduo. Come ben sappiamo, nell&#8217;era dell&#8217;informazione, questi confini sono sempre pi\u00f9 confusi. La ricerca della verit\u00e0 \u00e8 di conseguenza la ricerca della libert\u00e0, \u00a0una cosa \u00e8 profondamente collegata all&#8217;altra. Questo significa andare alla ricerca di un percorso che porti al compimento di s\u00e9:\u00a0 cio\u00e8 alla felicit\u00e0.<\/li>\n<\/ol>\n<ol start=\"8\">\n<li><strong>Un\u2019opera dal titolo \u201cPeople need heroes\u201d: perch\u00e9 l\u2019uomo ha bisogno di eroi? <\/strong><br \/>\nLa ricerca degli eroi \u00e8 insita nell&#8217;uomo che vede in essi una rappresentazione migliore di quello che si \u00e8. Una sublimazione dei propri desideri ed aspirazioni, la ricerca di un&#8217; emancipazione.\u00a0Quello che la gente ama pi\u00f9 dell&#8217;eroe \u00e8 vederlo cadere.<\/li>\n<\/ol>\n<ol start=\"9\">\n<li class=\"textnexttoimg\" style=\"text-align: justify;\"><strong>Ulteriore opera \u201cPeople\u2019s mind\u201d: cosa vi \u00e8 nella mente dell\u2019uomo contemporaneo secondo la tua visione? <\/strong><br \/>\nLa vita quotidiana \u00e8 piena di impegni, scadenze, appuntamenti, continui stimoli provocati anche dalle nuove tecnologie che necessitano un incessante lavoro di manutenzione continua. La mente delle persone \u00e8 sempre pi\u00f9 impegnata in un ritmo stressante tra tutte queste incombenze risultando sempre pi\u00f9 spesso confusa e priva del tempo per poter fare quello per cui \u00e8 stata creata: cio\u00e8 per pensare.<\/li>\n<\/ol>\n<ol start=\"10\">\n<li class=\"textnexttoimg\" style=\"text-align: justify;\"><strong>In cosa consiste la crisi d\u2019identit\u00e0 dell\u2019uomo che esprimi nelle tue opere?\u00a0<\/strong><br \/>\nTutte le persone indossano maschere. L&#8217;identit\u00e0 \u00e8 spesso legata all&#8217;ambiente sociale nel quale ci si trova. Nascondere la nostra personalit\u00e0 porta con s\u00e9 qualcosa di drammatico e comico che da sempre viene raccontato da artisti, scrittori e drammaturghi.<\/li>\n<\/ol>\n<ol start=\"11\">\n<li class=\"textnexttoimg\" style=\"text-align: justify;\"><strong>Hai dedicato molte opere all\u2019atmosfera circense. Cosa rappresenta per te?<br \/>\n<\/strong>Il Circo che ho rappresentato \u00e8 la nostra societ\u00e0. Luoghi dove vengono mostrate le diversit\u00e0 degli uomini per guadagnare soldi facili. Il circo come metafora della vita dell&#8217;uomo tra peccato e possibilit\u00e0 di redenzione.<\/li>\n<\/ol>\n<ol start=\"12\">\n<li class=\"textnexttoimg\" style=\"text-align: justify;\"><strong>Nel tuo Manifesto fragilista affermi: \u201c<em>Fragile \u00e8 l\u2019uomo. La consapevolezza della sua fragilit\u00e0 pu\u00f2 aiutarlo ad evolvere. Siamo involucro della delicatezza, della fragilit\u00e0 delle cose, delle emozioni<\/em>\u201d. In che modo la fragilit\u00e0 pu\u00f2 aiutare l\u2019uomo ad evolvere? <\/strong><br \/>\nNon penso che essere fragili voglia dire essere deboli, la fragilit\u00e0 \u00e8 anche nella vita che nasce e che pu\u00f2 crescere come possibilit\u00e0 di cambiamento.<\/li>\n<\/ol>\n<ol start=\"13\">\n<li class=\"textnexttoimg\" style=\"text-align: justify;\"><strong>\u201cWe can change the world\u201d, tua famosa collezione e grande messaggio soprattutto per i giovani studenti dell\u2019Accademia. <\/strong><br \/>\nLa storia di come nasce questa serie \u00e8 del tutto particolare. Nel ripulire la cantina mi sono imbattuto in un vecchio proiettore super 8, un modello in voga negli anni \u201960. Sul fondo del suo scatolone ho scorto un nastro un poco stropicciato, qualche metro di pellicola in tutto. Dopo aver verificato il suo funzionamento, ho riavvolto il nastro sulla bobina e, nel buio della stanza, la luce dell\u2019apparecchio ha ridato vita ad un vecchio filmato per pochi secondi. Nell\u2019immagine proiettata sulla parete per qualche istante \u00e8 apparso un globo su cui campeggiava la scritta: \u201cYou can change the World\u201d<strong>: <\/strong>\u201cPuoi cambiare il Mondo&#8221;. Il rumore del motorino che girava, e girava, e l\u2019odore della celluloide riscaldata dalla lampada mi hanno riportato in un tempo ed in un luogo che avevo ormai dimenticato, o almeno cos\u00ec pensavo: la percezione di essere tornato ragazzo, di provare ancora il futuro sconosciuto dentro me. Ma la cosa pi\u00f9 sconvolgente era la intensa certezza di poter essere speciali, di poter cambiare le cose che non funzionano, di poter affermare i propri ideali. Non \u00e8 mio intento dare consigli o fornire indicazioni utili alla personale ricerca di stimoli che consentono la svolta verso il cambiamento. Mi limiter\u00f2, come del resto sempre faccio, a parlare con le mie immagini, i miei colori, i miei segni e rimandi, per condurre l\u2019osservatore all\u2019ascolto di quella parte profonda e dimenticata che va oltre lo specchio interiore, annebbiata dal tempo e dalle disillusioni, aiutandolo se possibile a tornare, anche solo per qualche istante, nel mondo della sacra ingenuit\u00e0 quando ancora si credeva nella possibilit\u00e0 di essere, o almeno di provare ad essere, il cambiamento.<\/li>\n<\/ol>\n<ol start=\"14\">\n<li class=\"textnexttoimg\" style=\"text-align: justify;\"><strong>Prossimi progetti? <\/strong><br \/>\nLa nuova serie di quadri sar\u00e0 intitolata &#8216;Lie to Me&#8217; (mentimi). Una serie dedicata a tutte le persone che preferiscono vivere e credere alle bugie. Una scelta che spesso \u00e8 pi\u00f9 facile e comoda del guardare in faccia la realt\u00e0. E poi tra qualche mese arriver\u00e0, dopo oltre un anno di lavoro, il momento di mettere in scena uno spettacolo che sfrutta la scenografia virtuale: ViSet Project &#8211; Creative Europe, \u00a0sul quale ho collaborato sia come Project Manager ma anche e soprattutto come artista per idearne l&#8217;aspetto artistico, creativo e visuale. \u00a0Il progetto vede come capofila LABA (Libera Accademia di Belle Arti) e coinvolge studenti e docenti (Andrea Gentili, Enzo Gentile e Paolo Servi) impegnandoli in un tour su quattro paesi europei: Italia, Inghilterra, Spagna e Serbia. Un nuovo tipo di esperienza artistica che mi riempie di soddisfazioni.<\/li>\n<\/ol>\n<\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Italiano. For the sake of viewer convenience, the content is shown below in the alternative language. You may click the link to switch the active language. L\u2019artista. Breve biografia. Nasce nel 1967 a Milano. La sua passione per le arti figurative ed in <a href=\"https:\/\/artblobs.com\/en\/2016\/01\/interview-with-the-artist-massimo-balestrini\/\" class=\"btn-link\">Continue Reading<i class=\"ion-ios-arrow-right\"><\/i><\/a><\/p>\n","protected":false},"author":63,"featured_media":3000,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[601],"tags":[301,502,506,462,503,500,497,498,445,501,505,504,507,499],"class_list":["post-3002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","tag-arte-contemporanea","tag-cosmopolis","tag-information-war","tag-intervista","tag-learning-to-fly","tag-mainstream","tag-massimo-balestrini","tag-mixed-media","tag-pittura","tag-the-magic-door","tag-the-time-machine","tag-thoughts","tag-womens-quest","tag-you-can-change-the-world"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Interview with the artist Massimo Balestrini - ARt blobs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/artblobs.com\/it\/?p=3002\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interview with the artist Massimo Balestrini - ARt blobs\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in Italiano. For the sake of viewer convenience, the content is shown below in the alternative language. You may click the link to switch the active language. L\u2019artista. Breve biografia. Nasce nel 1967 a Milano. La sua passione per le arti figurative ed in Continue Reading\" \/>\n<meta property=\"og:url\" content=\"https:\/\/artblobs.com\/it\/?p=3002\" \/>\n<meta property=\"og:site_name\" content=\"ARt blobs\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-30T11:42:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-06T21:58:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/you_can_change_the_world_-_home.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1150\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anna Mattedi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna Mattedi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/artblobs.com\/it\/?p=3002#article\",\"isPartOf\":{\"@id\":\"https:\/\/artblobs.com\/it\/?p=3002\"},\"author\":{\"name\":\"Anna Mattedi\",\"@id\":\"https:\/\/artblobs.com\/en\/#\/schema\/person\/edba8ae3089048bdaa79e08f68bb4dbc\"},\"headline\":\"Interview with the artist Massimo Balestrini\",\"datePublished\":\"2016-01-30T11:42:29+00:00\",\"dateModified\":\"2023-07-06T21:58:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/artblobs.com\/it\/?p=3002\"},\"wordCount\":1477,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/artblobs.com\/en\/#\/schema\/person\/edba8ae3089048bdaa79e08f68bb4dbc\"},\"keywords\":[\"Contemporary art\",\"Cosmopolis\",\"Information war\",\"interview\",\"Learning to Fly\",\"Mainstream\",\"Massimo Balestrini\",\"Mixed media\",\"painting\",\"The magic door\",\"The time machine\",\"Thoughts\",\"Women's quest\",\"You can change the world\"],\"articleSection\":[\"Events\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/artblobs.com\/it\/?p=3002#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/artblobs.com\/it\/?p=3002\",\"url\":\"https:\/\/artblobs.com\/it\/?p=3002\",\"name\":\"Interview with the artist Massimo Balestrini - ARt blobs\",\"isPartOf\":{\"@id\":\"https:\/\/artblobs.com\/en\/#website\"},\"datePublished\":\"2016-01-30T11:42:29+00:00\",\"dateModified\":\"2023-07-06T21:58:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/artblobs.com\/it\/?p=3002#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/artblobs.com\/it\/?p=3002\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/artblobs.com\/it\/?p=3002#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/artblobs.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La parola all&#8217;artista. Intervista a Massimo Balestrini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/artblobs.com\/en\/#website\",\"url\":\"https:\/\/artblobs.com\/en\/\",\"name\":\"ARt blobs\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/artblobs.com\/en\/#\/schema\/person\/edba8ae3089048bdaa79e08f68bb4dbc\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/artblobs.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/artblobs.com\/en\/#\/schema\/person\/edba8ae3089048bdaa79e08f68bb4dbc\",\"name\":\"Anna Mattedi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/artblobs.com\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/artblobs.com\/wp-content\/uploads\/2018\/05\/cropped-logo-big-1.png\",\"contentUrl\":\"https:\/\/artblobs.com\/wp-content\/uploads\/2018\/05\/cropped-logo-big-1.png\",\"width\":250,\"height\":218,\"caption\":\"Anna Mattedi\"},\"logo\":{\"@id\":\"https:\/\/artblobs.com\/en\/#\/schema\/person\/image\/\"},\"sameAs\":[\"https:\/\/artblobs.com\/chi-sono\"],\"url\":\"https:\/\/artblobs.com\/en\/author\/anna-mattedi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interview with the artist Massimo Balestrini - ARt blobs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/artblobs.com\/it\/?p=3002","og_locale":"en_US","og_type":"article","og_title":"Interview with the artist Massimo Balestrini - ARt blobs","og_description":"Sorry, this entry is only available in Italiano. For the sake of viewer convenience, the content is shown below in the alternative language. You may click the link to switch the active language. L\u2019artista. Breve biografia. Nasce nel 1967 a Milano. La sua passione per le arti figurative ed in Continue Reading","og_url":"https:\/\/artblobs.com\/it\/?p=3002","og_site_name":"ARt blobs","article_published_time":"2016-01-30T11:42:29+00:00","article_modified_time":"2023-07-06T21:58:15+00:00","og_image":[{"width":1150,"height":400,"url":"https:\/\/artblobs.com\/wp-content\/uploads\/2016\/01\/you_can_change_the_world_-_home.jpeg","type":"image\/jpeg"}],"author":"Anna Mattedi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Anna Mattedi","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/artblobs.com\/it\/?p=3002#article","isPartOf":{"@id":"https:\/\/artblobs.com\/it\/?p=3002"},"author":{"name":"Anna Mattedi","@id":"https:\/\/artblobs.com\/en\/#\/schema\/person\/edba8ae3089048bdaa79e08f68bb4dbc"},"headline":"Interview with the artist Massimo Balestrini","datePublished":"2016-01-30T11:42:29+00:00","dateModified":"2023-07-06T21:58:15+00:00","mainEntityOfPage":{"@id":"https:\/\/artblobs.com\/it\/?p=3002"},"wordCount":1477,"commentCount":1,"publisher":{"@id":"https:\/\/artblobs.com\/en\/#\/schema\/person\/edba8ae3089048bdaa79e08f68bb4dbc"},"keywords":["Contemporary art","Cosmopolis","Information war","interview","Learning to Fly","Mainstream","Massimo Balestrini","Mixed media","painting","The magic door","The time machine","Thoughts","Women's quest","You can change the world"],"articleSection":["Events"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/artblobs.com\/it\/?p=3002#respond"]}]},{"@type":"WebPage","@id":"https:\/\/artblobs.com\/it\/?p=3002","url":"https:\/\/artblobs.com\/it\/?p=3002","name":"Interview with the artist Massimo Balestrini - ARt blobs","isPartOf":{"@id":"https:\/\/artblobs.com\/en\/#website"},"datePublished":"2016-01-30T11:42:29+00:00","dateModified":"2023-07-06T21:58:15+00:00","breadcrumb":{"@id":"https:\/\/artblobs.com\/it\/?p=3002#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/artblobs.com\/it\/?p=3002"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/artblobs.com\/it\/?p=3002#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/artblobs.com\/en\/"},{"@type":"ListItem","position":2,"name":"La parola all&#8217;artista. Intervista a Massimo Balestrini"}]},{"@type":"WebSite","@id":"https:\/\/artblobs.com\/en\/#website","url":"https:\/\/artblobs.com\/en\/","name":"ARt blobs","description":"","publisher":{"@id":"https:\/\/artblobs.com\/en\/#\/schema\/person\/edba8ae3089048bdaa79e08f68bb4dbc"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/artblobs.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/artblobs.com\/en\/#\/schema\/person\/edba8ae3089048bdaa79e08f68bb4dbc","name":"Anna Mattedi","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/artblobs.com\/en\/#\/schema\/person\/image\/","url":"https:\/\/artblobs.com\/wp-content\/uploads\/2018\/05\/cropped-logo-big-1.png","contentUrl":"https:\/\/artblobs.com\/wp-content\/uploads\/2018\/05\/cropped-logo-big-1.png","width":250,"height":218,"caption":"Anna Mattedi"},"logo":{"@id":"https:\/\/artblobs.com\/en\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/artblobs.com\/chi-sono"],"url":"https:\/\/artblobs.com\/en\/author\/anna-mattedi\/"}]}},"_links":{"self":[{"href":"https:\/\/artblobs.com\/en\/wp-json\/wp\/v2\/posts\/3002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artblobs.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/artblobs.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/artblobs.com\/en\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/artblobs.com\/en\/wp-json\/wp\/v2\/comments?post=3002"}],"version-history":[{"count":18,"href":"https:\/\/artblobs.com\/en\/wp-json\/wp\/v2\/posts\/3002\/revisions"}],"predecessor-version":[{"id":7767,"href":"https:\/\/artblobs.com\/en\/wp-json\/wp\/v2\/posts\/3002\/revisions\/7767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artblobs.com\/en\/wp-json\/wp\/v2\/media\/3000"}],"wp:attachment":[{"href":"https:\/\/artblobs.com\/en\/wp-json\/wp\/v2\/media?parent=3002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/artblobs.com\/en\/wp-json\/wp\/v2\/categories?post=3002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/artblobs.com\/en\/wp-json\/wp\/v2\/tags?post=3002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}